{"id":12255,"date":"2024-05-03T11:56:08","date_gmt":"2024-05-03T09:56:08","guid":{"rendered":"https:\/\/hsnordhausen.artemis.wpspace.me\/hsn\/?post_type=forschungsprojekt&#038;p=12255"},"modified":"2024-09-17T14:50:18","modified_gmt":"2024-09-17T12:50:18","slug":"hike-university-incubator-for-entrepreneurship-nordhausen","status":"publish","type":"forschungsprojekt","link":"https:\/\/hs-nordhausen.greydsuite.de\/en\/forschungsprojekt\/hike-hochschulinkubator-fuer-entrepreneurship-nordhausen\/","title":{"rendered":"University Incubator for Entrepreneurship Nordhausen"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"template":"","meta":{"_piecal_is_recurring":false,"_piecal_recurring_interval":1,"_piecal_recurring_frequency":"","_piecal_recurring_exact_position":false,"_piecal_recurring_end":"","_piecal_color":"","_piecal_text_color":"","_piecal_global_color_master":false,"_piecal_rsets":"[]","_piecal_is_event":false,"_piecal_start_date":"","_piecal_end_date":"","_piecal_is_allday":false,"greyd_block_editor_preview":[],"pgc_sgb_lightbox_settings":""},"forschungsprojekt_category":[1375],"forschungsprojekt_tag":[],"forschungsgebiet":[1376],"zielgruppen":[],"kontakt-zuordnung":[],"projekt":[1425],"studienbereich":[868],"institut-oder-einric":[678,1491],"fachbereich":[591],"wf_forschungsprojekt_folders":[1527],"ppma_author":[1400],"class_list":["post-12255","forschungsprojekt","type-forschungsprojekt","status-publish","hentry","forschungsprojekt_category-angezeigte-projekte","forschungsgebiet-n-a","projekt-hike","studienbereich-n-a","institut-oder-einric-ipmg-institut-fuer-public-management-und-governance","institut-oder-einric-referat-fuer-forschung-und-wissenschaft","fachbereich-fb-wirtschafts-und-sozialwissenschaften"],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hs-nordhausen.greydsuite.de\/en\/wp-json\/wp\/v2\/forschungsprojekt\/12255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hs-nordhausen.greydsuite.de\/en\/wp-json\/wp\/v2\/forschungsprojekt"}],"about":[{"href":"https:\/\/hs-nordhausen.greydsuite.de\/en\/wp-json\/wp\/v2\/types\/forschungsprojekt"}],"author":[{"embeddable":true,"href":"https:\/\/hs-nordhausen.greydsuite.de\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/hs-nordhausen.greydsuite.de\/en\/wp-json\/wp\/v2\/media?parent=12255"}],"wp:term":[{"taxonomy":"forschungsprojekt_category","embeddable":true,"href":"https:\/\/hs-nordhausen.greydsuite.de\/en\/wp-json\/wp\/v2\/forschungsprojekt_category?post=12255"},{"taxonomy":"forschungsprojekt_tag","embeddable":true,"href":"https:\/\/hs-nordhausen.greydsuite.de\/en\/wp-json\/wp\/v2\/forschungsprojekt_tag?post=12255"},{"taxonomy":"forschungsgebiet","embeddable":true,"href":"https:\/\/hs-nordhausen.greydsuite.de\/en\/wp-json\/wp\/v2\/forschungsgebiet?post=12255"},{"taxonomy":"zielgruppen","embeddable":true,"href":"https:\/\/hs-nordhausen.greydsuite.de\/en\/wp-json\/wp\/v2\/zielgruppen?post=12255"},{"taxonomy":"kontakt-zuordnung","embeddable":true,"href":"https:\/\/hs-nordhausen.greydsuite.de\/en\/wp-json\/wp\/v2\/kontakt-zuordnung?post=12255"},{"taxonomy":"projekt","embeddable":true,"href":"https:\/\/hs-nordhausen.greydsuite.de\/en\/wp-json\/wp\/v2\/projekt?post=12255"},{"taxonomy":"studienbereich","embeddable":true,"href":"https:\/\/hs-nordhausen.greydsuite.de\/en\/wp-json\/wp\/v2\/studienbereich?post=12255"},{"taxonomy":"institut-oder-einric","embeddable":true,"href":"https:\/\/hs-nordhausen.greydsuite.de\/en\/wp-json\/wp\/v2\/institut-oder-einric?post=12255"},{"taxonomy":"fachbereich","embeddable":true,"href":"https:\/\/hs-nordhausen.greydsuite.de\/en\/wp-json\/wp\/v2\/fachbereich?post=12255"},{"taxonomy":"wf_forschungsprojekt_folders","embeddable":true,"href":"https:\/\/hs-nordhausen.greydsuite.de\/en\/wp-json\/wp\/v2\/wf_forschungsprojekt_folders?post=12255"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/hs-nordhausen.greydsuite.de\/en\/wp-json\/wp\/v2\/ppma_author?post=12255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}